{"id":302,"date":"2016-06-24T11:05:55","date_gmt":"2016-06-24T09:05:55","guid":{"rendered":"http:\/\/blog.nimmerfall.info\/wpm\/?p=302"},"modified":"2016-06-24T14:19:16","modified_gmt":"2016-06-24T12:19:16","slug":"synchronisationsprobleme-bei-onedrive4business-per-loeschen-des-caches-loesen","status":"publish","type":"post","link":"http:\/\/blog.nimmerfall.info\/wpm\/blog\/synchronisationsprobleme-bei-onedrive4business-per-loeschen-des-caches-loesen\/","title":{"rendered":"Synchronisationsprobleme bei OneDrive4Business per L\u00f6schen des Caches l\u00f6sen"},"content":{"rendered":"<p>Leider hatte ich immer wieder Probleme bei der Synchronisation von Dateien, die ich im OneDrive for Business-Ordner abgelegt habe. Neben den Problemen, die mit unerlaubten Zeichen im Dateinamen, L\u00e4nge des Dateinamens etc. zusammenh\u00e4ngen, fiel mir auf, dass es h\u00e4ufig zu Synchronisationsfehlern nach Abst\u00fcrzen in einer der Office-Desktopapplikationen kam.<\/p>\n<p>Die Recherche mittels Google f\u00fchrte mich zu folgender L\u00f6sung aus einem <a href=\"http:\/\/answers.microsoft.com\/de-de\/msoffice\/forum\/msoffice_o365legacy-mso_oapps\/synchronisationsprobleme-onedrive-for-business\/85129701-c228-48d1-be52-022561bc143a\">Microsoft User Forum<\/a>:<!--more--><br \/>\nBitte die Synchronisation von allen Bibliotheken beenden.<\/p>\n<p>Den Task Manager \u00f6ffnen und die folgenden Vorg\u00e4nge stoppen: (Da dies im Taskmanager von Windows 10 nicht ganz so leicht zu finden ist, habe ich <a href=\"http:\/\/www.softwareok.de\/?seite=faq-Windows-Console&amp;faq=8#1\">HIER <\/a>eine Beschreibung gefunden, wie man die Tasks \u00fcber die Kommandozeile beenden kann)<\/p>\n<ul>\n<li>groove.exe<\/li>\n<li>msosync.exe<\/li>\n<li>msouc.exe<\/li>\n<li>csisyncclinet.exe<\/li>\n<li>winword.exe<\/li>\n<li>excel.exe<\/li>\n<li>powerpnt.exe<\/li>\n<\/ul>\n<p>Dann bitte den Comand Prompt (Eingabeaufforderung)starten und die folgenden Befehle einen nachdem anderen ausf\u00fchren, um den Cache zu l\u00f6schen:<\/p>\n<p>cd %USERPROFILE%\\AppData\\Local\\Microsoft\\Office\\16.0\\<\/p>\n<p>rmdir OfficeFileCache \/s<\/p>\n<p>cd %USERPROFILE%\\AppData\\Local\\Microsoft\\Office\\<\/p>\n<p>rmdir Spw \/s<\/p>\n<p>Dann \u00f6ffne die SharePoint Bibliothek und starte die Synchronisation von dort \u00fcber die Schaltf\u00e4che &#8222;Synchonisieren&#8220;. Daf\u00fcr muss im SharePoint Admin Center \/Einstellungen\/ die Option Schaltfl\u00e4che &#8222;OneDrive synchronisieren&#8220; auf &#8222;Alten Client starten&#8220; gesetzt werden.<\/p>\n<p>Eine Batch-Datei, die\u00a0laut Autor die selben Schritte erledigt, habe ich <a href=\"https:\/\/www.sepago.de\/blog\/2016\/01\/21\/onedrive-for-business-fehler-beim-synchronisieren-von-dateien-dateien-werden-nicht\">HIER <\/a>gefunden.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Die Benutzung der angef\u00fchrten L\u00f6sungen erfolgt ausdr\u00fccklich auf eigene Verantwortung!<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leider hatte ich immer wieder Probleme bei der Synchronisation von Dateien, die ich im OneDrive for Business-Ordner abgelegt habe. Neben den Problemen, die mit unerlaubten Zeichen im Dateinamen, L\u00e4nge des Dateinamens etc. zusammenh\u00e4ngen, fiel mir auf, dass es h\u00e4ufig zu Synchronisationsfehlern nach Abst\u00fcrzen in einer der Office-Desktopapplikationen kam. Die Recherche mittels Google f\u00fchrte mich zu &#8230;<a class=\"post-readmore\" href=\"http:\/\/blog.nimmerfall.info\/wpm\/blog\/synchronisationsprobleme-bei-onedrive4business-per-loeschen-des-caches-loesen\/\">read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/blog.nimmerfall.info\/wpm\/wp-json\/wp\/v2\/posts\/302"}],"collection":[{"href":"http:\/\/blog.nimmerfall.info\/wpm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blog.nimmerfall.info\/wpm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blog.nimmerfall.info\/wpm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blog.nimmerfall.info\/wpm\/wp-json\/wp\/v2\/comments?post=302"}],"version-history":[{"count":2,"href":"http:\/\/blog.nimmerfall.info\/wpm\/wp-json\/wp\/v2\/posts\/302\/revisions"}],"predecessor-version":[{"id":305,"href":"http:\/\/blog.nimmerfall.info\/wpm\/wp-json\/wp\/v2\/posts\/302\/revisions\/305"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/blog.nimmerfall.info\/wpm\/wp-json\/wp\/v2\/media\/303"}],"wp:attachment":[{"href":"http:\/\/blog.nimmerfall.info\/wpm\/wp-json\/wp\/v2\/media?parent=302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blog.nimmerfall.info\/wpm\/wp-json\/wp\/v2\/categories?post=302"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blog.nimmerfall.info\/wpm\/wp-json\/wp\/v2\/tags?post=302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}